{"id":721,"date":"2018-08-08T10:10:08","date_gmt":"2018-08-08T10:10:08","guid":{"rendered":"https:\/\/web.dev.abridia.com\/?page_id=721"},"modified":"2025-09-29T13:19:17","modified_gmt":"2025-09-29T13:19:17","slug":"nos-solutions","status":"publish","type":"page","link":"https:\/\/web.dev.abridia.com\/en\/nos-solutions\/","title":{"rendered":"Our digital solutions"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section style=\"\" class=\"vc_section\"><div style=\"\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc-hoverbox-wrapper  vc-hoverbox-shape--rounded vc-hoverbox-align--center vc-hoverbox-direction--default vc-hoverbox-width--100\"  ontouchstart=\"\">\n  <div class=\"vc-hoverbox\">\n    <div class=\"vc-hoverbox-inner\">\n      <div class=\"vc-hoverbox-block vc-hoverbox-front\" style=\"background-image: url(https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/07\/arbidia-tunisie--1024x684.jpg);\">\n        <div class=\"vc-hoverbox-block-inner vc-hoverbox-front-inner\">\n            <h2 style=\"text-align:center\">Towards the world of digitalization<\/h2>\n        <\/div>\n      <\/div>\n      <div class=\"vc-hoverbox-block vc-hoverbox-back\" style=\"background-color: #ebebeb;\">\n        <div class=\"vc-hoverbox-block-inner vc-hoverbox-back-inner\">\n            <h2 style=\"text-align:center\">Towards the world of digitalization<\/h2>\n            <p>Explore ABRIDIA's solutions, designed to digitalize, automate and secure transport and logistics\nmanagement.<\/p>\n\n            <div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" ><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-modern vc_btn3-color-grey\" href=\"https:\/\/web.dev.abridia.com\/en\/contact\/\" title=\"Request a demo\" target=\"_blank\">Request a demo<\/a><\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><div style=\"\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"iconbox style3 custom-hover\">\n\n\t<h5 class=\"box-title\">FREIGHTSURE, the intelligent, modular and 100% connected TMS solution<\/h5>\n\t<div class=\"box-detail\">\n\t\t<p>FREIGHTSURE, our Transport Management System (TMS), is the solution dedicated to transport\nmanagement. Powered by AI and IoT, it offers a flexible, customizable SaaS platform designed to turn your logistical challenges into sustainable competitive advantages.<\/p>\n\t\n\t<\/div>\n\t<div class=\"box-icon\"><img decoding=\"async\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/07\/FREIGHTSURE-la-solution-TMS-intelligente-modulaire-et-100-connectee.png\" alt=\"FREIGHTSURE, la solution TMS intelligente, modulaire et 100 % connect\u00e9e\" \/><\/div>\t\n\t\n\t\t<div class=\"box-readmore\">\n\t\t\t<a class=\"button no-bg\" href=\"https:\/\/web.dev.abridia.com\/en\/contact\/\">Request a demo<\/a>\n\t\t<\/div>\n<\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><div style=\"\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"row-inner\"><\/div><\/div><div style=\"\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">KEY FEATURES OF FREIGHTSURE<\/h2><\/header><p style=\"text-align: center;\">A modular, complete and scalable platform for optimized logistics management<\/p>\n<\/div><\/div><\/div><\/section><div class=\"wpb_images_carousel wpb_content_element vc_clearfix wpb_content_element wpb_animate_when_almost_visible wpb_fadeIn fadeIn\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-3-1784077121\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"5000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"3\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-mobile\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 21 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-reporting\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 20 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-stock\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 18 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-track\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 17 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-plan\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 16 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-order\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 15 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-navigator\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 14 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-facturation\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 19 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-3-1784077121\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-3-1784077121\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey vc_custom_1755858770228 wpb_content_element  vc_custom_1755858770228 wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">Tangible results for your operations<\/h2><\/header><p style=\"text-align: center;\">FREIGHTSURE: measurable benefits at every step<\/p>\n<\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><div style=\"\" class=\"vc_row wpb_row vc_row-fluid\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">KEY FEATURES OF FREIGHTSURE<\/h2><\/header><p style=\"text-align: center;\">A modular, complete and scalable platform for optimized logistics management<\/p>\n<\/div><\/div><\/div><\/section><div class=\"wpb_images_carousel wpb_content_element vc_clearfix wpb_content_element wpb_animate_when_almost_visible wpb_fadeIn fadeIn\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-4-1784077121\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"5000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-mobile\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 21 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-21-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-reporting\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 20 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-20-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-stock\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 18 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-18-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-track\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 17 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-17-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-plan\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 16 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-16-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-order\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 15 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-15-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-navigator\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 14 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-14-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/asqhub.com\/arbidia\/freight-facturation\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"416\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy.png\" class=\"attachment-full\" alt=\"\" title=\"Artboard 19 copy\" srcset=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy.png 339w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy-244x300.png 244w, https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/Artboard-19-copy-10x12.png 10w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><a class=\"vc_left vc_carousel-control\" href=\"#vc_images-carousel-4-1784077121\" data-slide=\"prev\"><span class=\"icon-prev\"><\/span><\/a><a class=\"vc_right vc_carousel-control\" href=\"#vc_images-carousel-4-1784077121\" data-slide=\"next\"><span class=\"icon-next\"><\/span><\/a><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey vc_custom_1755858770228 wpb_content_element  vc_custom_1755858770228 wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">Tangible results for your operations<\/h2><\/header><p style=\"text-align: center;\">FREIGHTSURE: measurable benefits at every step<\/p>\n<\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><\/section><div style=\"background-position: center center !important;\" class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-top vc_row-flex\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md vc_cta3-icons-bottom  wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_custom_1757629738396\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">30%<\/h2><h4 style=\"color:#0A51DF;\">improvement in customer satisfaction<\/h4><\/header><\/div><\/div><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fa fa-solid fa-star\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-lg vc_cta3-icons-in-box vc_cta3-icons-bottom  wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_custom_1757628597688\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">50%<\/h2><h4 style=\"color:#0A51DF;\">faster invoice processing<\/h4><\/header><\/div><\/div><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_icon_element-align-left vc_icon_element-have-style\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-have-style-inner vc_icon_element-size-lg vc_icon_element-style-boxed vc_icon_element-background vc_icon_element-background-color-custom\"  style=\"background-color:\"><span class=\"vc_icon_element-icon fa fa-solid fa-money-bill-transfer\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md vc_cta3-icons-bottom  wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_custom_1757629796840\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">25%<\/h2><h4 style=\"color:#0A51DF;\">optimized use of your resources<\/h4><\/header><\/div><\/div><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fa fa-solid fa-paperclip\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><div style=\"background-position: center center !important;\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1752242415931 vc_row-o-content-middle vc_row-flex\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md vc_cta3-icons-bottom  wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_custom_1757629362543\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">15%<\/h2><h4 style=\"color:#0A51DF;\">reduction in your insurance premiums<\/h4><\/header><\/div><\/div><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon entypo-icon entypo-icon-briefcase\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md vc_cta3-icons-bottom  wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_custom_1757628571788\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">90%<\/h2><h4 style=\"color:#0A51DF;\">reduction in administrative tasks<\/h4><\/header><\/div><\/div><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fa fa-solid fa-paperclip\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-lg vc_cta3-icons-in-box vc_cta3-icons-bottom  wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_custom_1757628837520\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#0A51DF;\">20%<\/h2><h4 style=\"color:#0A51DF;\">fuel savings<\/h4><\/header><\/div><\/div><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon wpb_animate_when_almost_visible wpb_fadeInLeft fadeInLeft vc_icon_element-align-left vc_icon_element-have-style\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-have-style-inner vc_icon_element-size-lg vc_icon_element-style-boxed vc_icon_element-background vc_icon_element-background-color-custom\"  style=\"background-color:\"><span class=\"vc_icon_element-icon fa fa-solid fa-truck\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><section style=\"\" class=\"vc_section\"><div style=\"\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1752241835930 vc_row-has-fill\"><div class=\"row-inner\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-custom vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-icon-size-md vc_cta3-icons-top vc_custom_1752241650685\" style=\"background-color:#FFFFFF;\"><div class=\"vc_cta3-icons\"><div class=\"vc_icon_element vc_icon_element-outer vc_do_icon vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-custom vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon fa fa-solid fa-arrow-trend-up\" style=\"color:#0AE8C8 !important\"><\/span><\/div><\/div><\/div><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2 style=\"color:#FFFFFF;\">WHAT FREIGHTSURE TMS OFFERS EXTRA<\/h2><\/header><\/div><\/div><\/div><\/section><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"lvca-accordion lvca-style1\" data-toggle=\"false\" data-expanded=\"false\"><div class=\"lvca-panel\" id=\"\"><div class=\"lvca-panel-title\">An intuitive and user-friendly interface:<\/div><div class=\"lvca-panel-content\"><\/p>\n<div class=\"box-detail\">\n<p>A smooth user experience designed to facilitate adoption and maximize productivity.<\/p>\n<\/div>\n<p><\/div><\/div><!-- .lvca-panel --><div class=\"lvca-panel\" id=\"\"><div class=\"lvca-panel-title\">Full and secure interoperability:<\/div><div class=\"lvca-panel-content\"><\/p>\n<div class=\"box-detail\">\n<p>Integrates seamlessly with your existing systems (ERP, WMS, OMS, etc.) for reliable data exchange.<\/p>\n<\/div>\n<p><\/div><\/div><!-- .lvca-panel --><div class=\"lvca-panel\" id=\"\"><div class=\"lvca-panel-title\">Advanced IoT integration:<\/div><div class=\"lvca-panel-content\"><\/p>\n<div class=\"box-detail\">\n<p>Connect motion sensors, GPS, fuel level sensors and other devices for accurate real-time monitoring.<\/p>\n<\/div>\n<p><\/div><\/div><!-- .lvca-panel --><div class=\"lvca-panel\" id=\"\"><div class=\"lvca-panel-title\">No upfront implementation cost:<\/div><div class=\"lvca-panel-content\"><\/p>\n<div class=\"box-detail\">\n<p>Benefit from a turnkey solution with no upfront investment to accelerate your digital transformation without financial risk.<\/p>\n<\/div>\n<p><\/div><\/div><!-- .lvca-panel --><div class=\"lvca-panel\" id=\"\"><div class=\"lvca-panel-title\">Personalized support:<\/div><div class=\"lvca-panel-content\"><\/p>\n<div class=\"box-detail\">\n<p>Dedicated support, tailored training and responsive customer service to guide you through every step\nof your transformation.<\/p>\n<\/div>\n<p><\/div><\/div><!-- .lvca-panel --><\/div><!-- .lvca-accordion --><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/web.dev.abridia.com\/wp-content\/uploads\/2025\/09\/arbidia-solution-440x440.jpg\" width=\"440\" height=\"440\" alt=\"arbidia solution\" title=\"arbidia solution\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div>","protected":false},"excerpt":{"rendered":"Vers l'univers de la digitalisation Vers l'univers de la digitalisation Explorez l\u2019univers des solutions ABRIDIA, pens\u00e9es pour digitaliser, automatiser et s\u00e9curiser la gestion du transport et de la logistique. Demander une d\u00e9mo FREIGHTSURE, la solution TMS intelligente, modulaire et 100 % connect\u00e9e FFREIGHTSURE, notre Transport Management System (TMS) est la solution d\u00e9di\u00e9e \u00e0 la gestion [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tmpl\/template-fullwidth.php","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-721","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/pages\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/comments?post=721"}],"version-history":[{"count":82,"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/pages\/721\/revisions"}],"predecessor-version":[{"id":2696,"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/pages\/721\/revisions\/2696"}],"wp:attachment":[{"href":"https:\/\/web.dev.abridia.com\/en\/wp-json\/wp\/v2\/media?parent=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}